{"id":1470,"date":"2018-02-26T10:09:43","date_gmt":"2018-02-26T10:09:43","guid":{"rendered":"https:\/\/livewp.site\/wp\/md\/sunergy\/?page_id=1470"},"modified":"2022-01-22T16:13:55","modified_gmt":"2022-01-22T16:13:55","slug":"team-member","status":"publish","type":"page","link":"https:\/\/www.stagnonekiteboarding.com\/en\/team-member\/","title":{"rendered":"Team"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row-wrapper vc_custom_1642865845912\"><div class=\"container\"><div class=\"vc_row wpb_row vc_row-fluid vc_row-has-fill\"  ><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner vc_custom_1526025460763\"><div class=\"wpb_wrapper\"><div class=\"gt3_spacing gt3_spacing-height_mobile-on\"><div class=\"gt3_spacing-height gt3_spacing-height_default\" style=\"height:80px;\"><\/div> <div class=\"gt3_spacing-height gt3_spacing-height_mobile\" style=\"height:0px;\"><\/div><\/div>  \r\n<div data-color=\"#ffffff\" class=\"gt3_custom_text\" style=\"color:#27323d;font-size: 30px; line-height: 155%; \"><strong>We Have Best Instructors<\/strong><\/div>  \r\n<div class=\"gt3_spacing\"><div class=\"gt3_spacing-height gt3_spacing-height_default\" style=\"height:18px;\"><\/div><\/div>  \r\n<div data-color=\"#ffffff\" class=\"gt3_custom_text\" style=\"color:#737d84;font-size: 16px; line-height: 190%; \">\n<h3><strong>Tutti gli istruttori di Stagnone kiteboarding\u00a0 hanno certificazioni Internazionali\u00a0<\/strong><\/h3>\n<p>Tutti i nostri istruttori sono in possesso dei requisiti della International Kiteboarding Organization, la pi\u00f9 prestigiosa organizzazione mondiale nell\u2019insegnamento del kitesurf, e grazie alla loro esperienza ti faranno progredire in maniera rilassata ma estremamente professionale, seguendo la metodologia pi\u00f9 rapida e sicura.<\/p>\n<p>Ma non solo, tutto il personale, nonostante i requisiti, hanno dovuto superare una selezione tra moltissimi direttamente da Antonio Gaudini, Formatore e Allenatore internazionale.<\/p>\n<p>Il nostro Team \u00e8 in possesso di<\/p>\n<ul class=\"gt3_list_angle_down\" style=\"margin-left: 22px; padding-top: 21px;\">\n<li>Current CPR\/First Aid Certification<\/li>\n<li>Water Safety Certification<\/li>\n<li>Esperienza di almeno 3 anni di insegnamento<\/li>\n<li>Formati da Master Class internazionali<\/li>\n<\/ul>\n<\/div>  \r\n<div class=\"gt3_spacing\"><div class=\"gt3_spacing-height gt3_spacing-height_default\" style=\"height:27px;\"><\/div><\/div>  \r\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row-wrapper vc_custom_1526028290261\"><div class=\"container\"><div class=\"vc_row wpb_row vc_row-fluid vc_row-has-fill\"  ><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner vc_custom_1522848871910\"><div class=\"wpb_wrapper\"><div class=\"gt3_spacing gt3_spacing-height_tablet-on gt3_spacing-height_mobile-on\"><div class=\"gt3_spacing-height gt3_spacing-height_default\" style=\"height:66px;\"><\/div> <div class=\"gt3_spacing-height gt3_spacing-height_tablet\" style=\"height:50px;\"><\/div> <div class=\"gt3_spacing-height gt3_spacing-height_mobile\" style=\"height:30px;\"><\/div><\/div>  \r\n\r\n\r\n<div class=\"vc_row\">\r\n    <div class=\"vc_col-sm-12 module_team  module_on_dark_bg\">\r\n    <h3 class=\"module-team_title\">Meet Our Team<\/h3><p>We want to make sure that you have the best experience possible out there in the ocean. Our team consists of local and international surfing enthusiasts. They like to embrace the surfing lifestyle and are not only soul surfers but are also qualified Water Safety Specialists, CPR &amp; First Aid certified!<\/p>    \t<div class=\"shortcode_team\">\r\n\t        <div class=\"items3\">\r\n\t        \t          <ul class=\"item_list\"  style=\"margin-right:-10px\" >\r\n\t         \t\t\r\n            <li class=\"item-team-member kitesurf-team\"  style=\"padding-right:10px;padding-bottom:10px\">\r\n                <div class=\"item_wrapper\">\r\n                    <div class=\"item\">\r\n                        <div class=\"team_img featured_img\">\r\n                            <span> <img decoding=\"async\"  src=\"https:\/\/www.stagnonekiteboarding.com\/wp-content\/uploads\/2017\/01\/antonio-gaudini-immagine-profilo-390x390.jpg\" alt=\"Antonio Gaudini\" \/><\/span>\r\n                        <\/div>\r\n                       <a class=\"team__link-to-single\" href=\"https:\/\/www.stagnonekiteboarding.com\/en\/team\/antonio-gaudini\/\"><\/a>\r\n\t\t\t\t\t\t<div class=\"member-icons\"><div class=\"team-icons\"><a href=\"https:\/\/www.facebook.com\/kitesurfing\" class=\"member-icon fa fa-facebook\"><\/a><a href=\"https:\/\/www.twitter.com\/kitesurfitalia\" class=\"member-icon fa fa-twitter\"><\/a><a href=\"https:\/\/www.instagram.com\/antonio_ktb\/\" class=\"member-icon fa fa-instagram\"><\/a><\/div><\/div>                        \r\n                        <div class=\"team-infobox\">\r\n                            <div class=\"team_title\">\r\n                                <h4><a href=\"https:\/\/www.stagnonekiteboarding.com\/en\/team\/antonio-gaudini\/\">Antonio Gaudini<\/a><\/h4><span class=\"team-positions\"><span>Master Instructor<\/span><\/span>\r\n                            <\/div>\r\n                            \r\n                        <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/li>\r\n            \r\n            <li class=\"item-team-member kitesurf-team\"  style=\"padding-right:10px;padding-bottom:10px\">\r\n                <div class=\"item_wrapper\">\r\n                    <div class=\"item\">\r\n                        <div class=\"team_img featured_img\">\r\n                            <span> <img decoding=\"async\"  src=\"https:\/\/www.stagnonekiteboarding.com\/wp-content\/uploads\/2017\/01\/david-ingiosi-390x390.jpg\" alt=\"David Ingiosi\" \/><\/span>\r\n                        <\/div>\r\n                       <a class=\"team__link-to-single\" href=\"https:\/\/www.stagnonekiteboarding.com\/en\/team\/david-ingiosi\/\"><\/a>\r\n\t\t\t\t\t\t<div class=\"member-icons\"><div class=\"team-icons\"><a href=\"#\" class=\"member-icon fa fa-facebook\"><\/a><a href=\"#\" class=\"member-icon fa fa-twitter\"><\/a><a href=\"#\" class=\"member-icon fa fa-instagram\"><\/a><a href=\"#\" class=\"member-icon fa fa-google-plus\"><\/a><\/div><\/div>                        \r\n                        <div class=\"team-infobox\">\r\n                            <div class=\"team_title\">\r\n                                <h4><a href=\"https:\/\/www.stagnonekiteboarding.com\/en\/team\/david-ingiosi\/\">David Ingiosi<\/a><\/h4><span class=\"team-positions\"><span>Instructor <\/span><\/span>\r\n                            <\/div>\r\n                            \r\n                        <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/li>\r\n            \r\n            <li class=\"item-team-member kitesurf-team\"  style=\"padding-right:10px;padding-bottom:10px\">\r\n                <div class=\"item_wrapper\">\r\n                    <div class=\"item\">\r\n                        <div class=\"team_img featured_img\">\r\n                            <span> <img decoding=\"async\"  src=\"https:\/\/www.stagnonekiteboarding.com\/wp-content\/uploads\/2017\/01\/Valentina-390x390.jpg\" alt=\"Valentina La Gioia\" \/><\/span>\r\n                        <\/div>\r\n                       <a class=\"team__link-to-single\" href=\"https:\/\/www.stagnonekiteboarding.com\/en\/team\/valentina-la-gioia\/\"><\/a>\r\n\t\t\t\t\t\t<div class=\"member-icons\"><div class=\"team-icons\"><a href=\"https:\/\/www.facebook.com\/barbara.delprete.5\" class=\"member-icon fa fa-facebook\"><\/a><a href=\"\/en\/www.instagram.com\/dabdlp\/\" class=\"member-icon fa fa-instagram\"><\/a><\/div><\/div>                        \r\n                        <div class=\"team-infobox\">\r\n                            <div class=\"team_title\">\r\n                                <h4><a href=\"https:\/\/www.stagnonekiteboarding.com\/en\/team\/valentina-la-gioia\/\">Valentina La Gioia<\/a><\/h4><span class=\"team-positions\"><span>Manager Senior & Istructor IKO <\/span><\/span>\r\n                            <\/div>\r\n                            \r\n                        <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/li>\r\n            \t            <\/ul>\r\n\t            <div class=\"clear\"><\/div>\r\n\t        <\/div>\r\n    \t<\/div>\r\n    <\/div>\r\n<\/div><div class=\"gt3_spacing gt3_spacing-height_mobile-on\"><div class=\"gt3_spacing-height gt3_spacing-height_default\" style=\"height:60px;\"><\/div> <div class=\"gt3_spacing-height gt3_spacing-height_mobile\" style=\"height:10px;\"><\/div><\/div>  \r\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row-wrapper vc_custom_1642867108928 gt3_mask_image\" style=\"-webkit-mask-image: url(https:\/\/www.stagnonekiteboarding.com\/wp-content\/uploads\/2018\/05\/pattern.png);    mask-image: url(https:\/\/www.stagnonekiteboarding.com\/wp-content\/uploads\/2018\/05\/pattern.png);    \"><div class=\"container\"><div class=\"vc_row wpb_row vc_row-fluid vc_row-has-fill\"  ><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"gt3_spacing gt3_spacing-height_mobile-on\"><div class=\"gt3_spacing-height gt3_spacing-height_default\" style=\"height:90px;\"><\/div> <div class=\"gt3_spacing-height gt3_spacing-height_mobile\" style=\"height:50px;\"><\/div><\/div>  \r\n<div data-color=\"#ffffff\" class=\"gt3_custom_text\" style=\"color:#ffffff;font-size: 30px; line-height: 100%; \">\n<p style=\"text-align: center;\"><strong>What People are Saying About Us<\/strong><\/p>\n<\/div>  \r\n<div class=\"gt3_spacing\"><div class=\"gt3_spacing-height gt3_spacing-height_default\" style=\"height:45px;\"><\/div><\/div>  \r\n\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center wpb_content_element\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"106\" height=\"12\" src=\"https:\/\/www.stagnonekiteboarding.com\/wp-content\/uploads\/2018\/05\/bg_title_zigzag_separator.png\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"bg_title_zigzag_separator\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"gt3_spacing\"><div class=\"gt3_spacing-height gt3_spacing-height_default\" style=\"height:23px;\"><\/div><\/div>  \r\n<div class=\"vc_row wpb_row vc_inner vc_row-fluid testi_02\" ><div class=\"wpb_column vc_column_container vc_col-sm-8 vc_col-sm-offset-2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_row\">\r\n    <div class=\"vc_col-sm-12 module_testimonial  active-carousel type4\" data-slides-per-line=\"1\" data-slider-fade=\"1\" data-autoplay-time=\"4000\">\r\n    \t<div class=\"module_content testimonials_list items1\">\r\n        \t\r\n            <div class=\"testimonials_rotator\">\r\n        <div class=\"testimonials_item\">\r\n            <div class=\"testimonial_item_wrapper\">\r\n                <div class=\"testimonials_content\">\r\n                    <div class=\"testimonials-text\"  style= \" color: #ffffff; font-size: 24px; line-height: 1.5;\"> \n<p style=\"text-align: center;\"><span>Non sai mai mai che tipo di condizioni troverai domani.\u00a0 Se vento forte con onda grande o mare piatto. Tutto quello che puoi fare \u00e8 sorridere perch\u00e8 anche domani sar\u00e0 un grande giorno per poter volare o surfare tra cielo e mare.<\/span><\/p>\n<\/div>\r\n                    <div class=\"testimonials_title\" style=\" color: #ffffff; font-size: 18px;\">Antonio Gaudini,<div class=\"testimonial_item_position\">Pioneer of kitesurfing<\/div><\/div>\r\n                    \r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n\r\n        <div class=\"testimonials_item\">\r\n            <div class=\"testimonial_item_wrapper\">\r\n                <div class=\"testimonials_content\">\r\n                    <div class=\"testimonials-text\"  style= \" color: #ffffff; font-size: 24px; line-height: 1.5;\"> \n<p style=\"text-align: center;\">Ci sono molti modi di vedere le cose, una di queste \u00e8 semplicemente sorridere alle emozioni che la vita pi\u00f2 regalarti, come quelle che ogni santa volta ti fa respirare il Kitesurf<\/p>\n<\/div>\r\n                    <div class=\"testimonials_title\" style=\" color: #ffffff; font-size: 18px;\">David Ingiosi,<div class=\"testimonial_item_position\">Istructor<\/div><\/div>\r\n                    \r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n<\/div><div class=\"clear\"><\/div>        <\/div>\r\n    <\/div>\r\n<\/div><\/div><\/div><\/div><\/div><div class=\"gt3_spacing gt3_spacing-height_mobile-on\"><div class=\"gt3_spacing-height gt3_spacing-height_default\" style=\"height:63px;\"><\/div> <div class=\"gt3_spacing-height gt3_spacing-height_mobile\" style=\"height:43px;\"><\/div><\/div>  \r\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row-wrapper vc_custom_1526039329221\"><div class=\"container\"><div class=\"vc_row wpb_row vc_row-fluid vc_row-has-fill\"  ><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"gt3_spacing gt3_spacing-height_mobile-on\"><div class=\"gt3_spacing-height gt3_spacing-height_default\" style=\"height:62px;\"><\/div> <div class=\"gt3_spacing-height gt3_spacing-height_mobile\" style=\"height:30px;\"><\/div><\/div>  \r\n<div class=\"vc_row\">\r\n    <div class=\"vc_col-sm-12 gt3_module_featured_posts blog_alignment_left   module_on_dark_bg blog_type3 items3  class_9860\" >\r\n\r\n        \r\n        <div class=\"gt3_module_title\"><div class=\"module_title_content\" ><strong>Latest News<\/strong><\/div><div class=\"external_link\"><a href=\"https:\/\/livewp.site\/wp\/md\/surfy\/blog-fullwidth\/\"   class=\"learn_more\">View All<span><\/span><\/a><\/div><\/div>\r\n        <div class=\"spacing_beetween_items_15\">\r\n\t\t\t\t\t<div class=\"blog_post_preview format-standard-image has_post_thumb\">\r\n                        <div class=\"item_wrapper\">\r\n                            <div class=\"blog_content\"><div class=\"blog_post_media\"><a href=\"https:\/\/www.stagnonekiteboarding.com\/en\/volo-ryanair-verona-trapani-stagnone-2026\/\"><img decoding=\"async\" src=\"https:\/\/www.stagnonekiteboarding.com\/wp-content\/uploads\/2024\/07\/Italian-Freestyle-Contest-Stagnone-2024-powered-STAGNONE-KITEBOARDING_1102-600x450.jpg\" alt=\"Nuovo volo Ryanair Verona Trapani: lo Stagnone \u00e8 ancora pi\u00f9 vicino nel 2026\" \/><\/a><span> <a href=\"https:\/\/www.stagnonekiteboarding.com\/en\/category\/uncategorized\/\">Uncategorized<\/a><\/span><\/div><div class=\"featured_post_info boxed_view\"><div class=\"listing_meta upper_text\"><span>by <a href=\"https:\/\/www.stagnonekiteboarding.com\/en\/author\/admin\/\">admin<\/a><\/span><span>17 April 2026<\/span><span><a href=\"https:\/\/www.stagnonekiteboarding.com\/en\/volo-ryanair-verona-trapani-stagnone-2026\/#respond\">0 comments<\/a><\/span><\/div><h4 class=\"blogpost_title\" ><a href=\"https:\/\/www.stagnonekiteboarding.com\/en\/volo-ryanair-verona-trapani-stagnone-2026\/\" >Nuovo volo Ryanair Verona Trapani: lo Stagnone \u00e8 ancora pi\u00f9 vicino nel 2026<span><\/span><\/a><\/h4><\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n\t\t\t\t\t<div class=\"blog_post_preview format-standard-image has_post_thumb\">\r\n                        <div class=\"item_wrapper\">\r\n                            <div class=\"blog_content\"><div class=\"blog_post_media\"><a href=\"https:\/\/www.stagnonekiteboarding.com\/en\/dove-alloggiare-stagnone-senza-macchina-kitesurf\/\"><img decoding=\"async\" src=\"https:\/\/www.stagnonekiteboarding.com\/wp-content\/uploads\/2024\/07\/Italian-Freestyle-Contest-Stagnone-2024-powered-STAGNONE-KITEBOARDING_1322-600x450.jpg\" alt=\"Dove alloggiare allo Stagnone senza macchina se vuoi fare kitesurf\" \/><\/a><span> <a href=\"https:\/\/www.stagnonekiteboarding.com\/en\/category\/kitesurfing\/\">Kitesurfing<\/a><\/span><\/div><div class=\"featured_post_info boxed_view\"><div class=\"listing_meta upper_text\"><span>by <a href=\"https:\/\/www.stagnonekiteboarding.com\/en\/author\/admin\/\">admin<\/a><\/span><span>10 April 2026<\/span><span><a href=\"https:\/\/www.stagnonekiteboarding.com\/en\/dove-alloggiare-stagnone-senza-macchina-kitesurf\/#respond\">0 comments<\/a><\/span><\/div><h4 class=\"blogpost_title\" ><a href=\"https:\/\/www.stagnonekiteboarding.com\/en\/dove-alloggiare-stagnone-senza-macchina-kitesurf\/\" >Dove alloggiare allo Stagnone senza macchina se vuoi fare kitesurf<span><\/span><\/a><\/h4><\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n\t\t\t\t\t<div class=\"blog_post_preview format-standard-image has_post_thumb\">\r\n                        <div class=\"item_wrapper\">\r\n                            <div class=\"blog_content\"><div class=\"blog_post_media\"><a href=\"https:\/\/www.stagnonekiteboarding.com\/en\/kitecamp-stagnone-maggio-2026-stagnone-kiteboarding\/\"><img decoding=\"async\" src=\"https:\/\/www.stagnonekiteboarding.com\/wp-content\/uploads\/2024\/07\/Italian-Freestyle-Contest-Stagnone-2024-powered-STAGNONE-KITEBOARDING_1446-600x450.jpg\" alt=\"Kitecamp Stagnone Maggio 2026: 5 giorni di kite, relax e lezioni con Stagnone Kiteboarding\" \/><\/a><span> <a href=\"https:\/\/www.stagnonekiteboarding.com\/en\/category\/kitecamp\/\">Kitecamp<\/a><\/span><\/div><div class=\"featured_post_info boxed_view\"><div class=\"listing_meta upper_text\"><span>by <a href=\"https:\/\/www.stagnonekiteboarding.com\/en\/author\/admin\/\">admin<\/a><\/span><span>9 April 2026<\/span><span><a href=\"https:\/\/www.stagnonekiteboarding.com\/en\/kitecamp-stagnone-maggio-2026-stagnone-kiteboarding\/#respond\">0 comments<\/a><\/span><\/div><h4 class=\"blogpost_title\" ><a href=\"https:\/\/www.stagnonekiteboarding.com\/en\/kitecamp-stagnone-maggio-2026-stagnone-kiteboarding\/\" >Kitecamp Stagnone Maggio 2026: 5 giorni di kite, relax e lezioni con Stagnone Kiteboarding<span><\/span><\/a><\/h4><\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div><\/div>    <\/div>\r\n<\/div>\r\n\r\n\r\n        <script type=\"text\/javascript\">\r\n            \"use strict\";\r\n            var custom_blog_css = \"\";\r\n            if (document.getElementById(\"custom_blog_styles\")) {\r\n                document.getElementById(\"custom_blog_styles\").innerHTML += custom_blog_css;\r\n            } else if (custom_blog_css !== \"\") {\r\n                document.head.innerHTML += '<style id=\"custom_blog_styles\" type=\"text\/css\">'+custom_blog_css+'<\/style>';\r\n            }\r\n        <\/script>\r\n    <\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div class=\"container\"><div class=\"vc_row-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid  gt3_brands_list\"  ><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"gt3_spacing gt3_spacing-height_mobile-on\"><div class=\"gt3_spacing-height gt3_spacing-height_default\" style=\"height:59px;\"><\/div> <div class=\"gt3_spacing-height gt3_spacing-height_mobile\" style=\"height:40px;\"><\/div><\/div>  \r\n\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center wpb_content_element\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"4500\" height=\"2288\" src=\"https:\/\/www.stagnonekiteboarding.com\/wp-content\/uploads\/2020\/11\/logo-iko-kitesurf.png\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"logo-iko kitesurf\" srcset=\"https:\/\/www.stagnonekiteboarding.com\/wp-content\/uploads\/2020\/11\/logo-iko-kitesurf.png 4500w, https:\/\/www.stagnonekiteboarding.com\/wp-content\/uploads\/2020\/11\/logo-iko-kitesurf-300x153.png 300w, https:\/\/www.stagnonekiteboarding.com\/wp-content\/uploads\/2020\/11\/logo-iko-kitesurf-1024x521.png 1024w, https:\/\/www.stagnonekiteboarding.com\/wp-content\/uploads\/2020\/11\/logo-iko-kitesurf-768x390.png 768w, https:\/\/www.stagnonekiteboarding.com\/wp-content\/uploads\/2020\/11\/logo-iko-kitesurf-1536x781.png 1536w, https:\/\/www.stagnonekiteboarding.com\/wp-content\/uploads\/2020\/11\/logo-iko-kitesurf-2048x1041.png 2048w, https:\/\/www.stagnonekiteboarding.com\/wp-content\/uploads\/2020\/11\/logo-iko-kitesurf-600x305.png 600w\" sizes=\"auto, (max-width: 4500px) 100vw, 4500px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"gt3_spacing gt3_spacing-height_mobile-on\"><div class=\"gt3_spacing-height gt3_spacing-height_default\" style=\"height:102px;\"><\/div> <div class=\"gt3_spacing-height gt3_spacing-height_mobile\" style=\"height:0px;\"><\/div><\/div>  \r\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"gt3_spacing gt3_spacing-height_mobile-on\"><div class=\"gt3_spacing-height gt3_spacing-height_default\" style=\"height:59px;\"><\/div> <div class=\"gt3_spacing-height gt3_spacing-height_mobile\" style=\"height:40px;\"><\/div><\/div>  \r\n\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center wpb_content_element\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.stagnonekiteboarding.com\/wp-content\/uploads\/2020\/11\/aki-150x150-1.png\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"aki-150x150\" srcset=\"https:\/\/www.stagnonekiteboarding.com\/wp-content\/uploads\/2020\/11\/aki-150x150-1.png 150w, https:\/\/www.stagnonekiteboarding.com\/wp-content\/uploads\/2020\/11\/aki-150x150-1-100x100.png 100w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"gt3_spacing gt3_spacing-height_mobile-on\"><div class=\"gt3_spacing-height gt3_spacing-height_default\" style=\"height:102px;\"><\/div> <div class=\"gt3_spacing-height gt3_spacing-height_mobile\" style=\"height:0px;\"><\/div><\/div>  \r\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"gt3_spacing gt3_spacing-height_mobile-on\"><div class=\"gt3_spacing-height gt3_spacing-height_default\" style=\"height:59px;\"><\/div> <div class=\"gt3_spacing-height gt3_spacing-height_mobile\" style=\"height:40px;\"><\/div><\/div>  \r\n\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center wpb_content_element\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.stagnonekiteboarding.com\/wp-content\/uploads\/2020\/11\/ultimate-150x150-1.png\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"ultimate-150x150\" srcset=\"https:\/\/www.stagnonekiteboarding.com\/wp-content\/uploads\/2020\/11\/ultimate-150x150-1.png 150w, https:\/\/www.stagnonekiteboarding.com\/wp-content\/uploads\/2020\/11\/ultimate-150x150-1-100x100.png 100w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"gt3_spacing gt3_spacing-height_mobile-on\"><div class=\"gt3_spacing-height gt3_spacing-height_default\" style=\"height:102px;\"><\/div> <div class=\"gt3_spacing-height gt3_spacing-height_mobile\" style=\"height:0px;\"><\/div><\/div>  \r\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"gt3_spacing gt3_spacing-height_mobile-on\"><div class=\"gt3_spacing-height gt3_spacing-height_default\" style=\"height:59px;\"><\/div> <div class=\"gt3_spacing-height gt3_spacing-height_mobile\" style=\"height:40px;\"><\/div><\/div>  \r\n\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center wpb_content_element\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"1134\" height=\"375\" src=\"https:\/\/www.stagnonekiteboarding.com\/wp-content\/uploads\/2021\/08\/Logo-Sunset-Wave-2021.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"Logo Sunset Wave 2021\" srcset=\"https:\/\/www.stagnonekiteboarding.com\/wp-content\/uploads\/2021\/08\/Logo-Sunset-Wave-2021.jpg 1134w, https:\/\/www.stagnonekiteboarding.com\/wp-content\/uploads\/2021\/08\/Logo-Sunset-Wave-2021-300x99.jpg 300w, https:\/\/www.stagnonekiteboarding.com\/wp-content\/uploads\/2021\/08\/Logo-Sunset-Wave-2021-1024x339.jpg 1024w, https:\/\/www.stagnonekiteboarding.com\/wp-content\/uploads\/2021\/08\/Logo-Sunset-Wave-2021-768x254.jpg 768w, https:\/\/www.stagnonekiteboarding.com\/wp-content\/uploads\/2021\/08\/Logo-Sunset-Wave-2021-600x198.jpg 600w\" sizes=\"auto, (max-width: 1134px) 100vw, 1134px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"gt3_spacing gt3_spacing-height_mobile-on\"><div class=\"gt3_spacing-height gt3_spacing-height_default\" style=\"height:102px;\"><\/div> <div class=\"gt3_spacing-height gt3_spacing-height_mobile\" style=\"height:60px;\"><\/div><\/div>  \r\n<\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Il Team dello Stagnone Kiteboarding \u00e8 composto da veri e propri professionisti del Kitesurf. Unici del suo genere. Scopri di pi\u00f9&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full-width.php","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-1470","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Team - Kitesurf Stagnone<\/title>\n<meta name=\"description\" content=\"Il Team dello Stagnone Kiteboarding \u00e8 composto da veri e propri professionisti del Kitesurf. Unici del suo genere. Scopri di pi\u00f9...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.stagnonekiteboarding.com\/en\/team-member\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Team - Kitesurf Stagnone\" \/>\n<meta property=\"og:description\" content=\"Il Team dello Stagnone Kiteboarding \u00e8 composto da veri e propri professionisti del Kitesurf. Unici del suo genere. Scopri di pi\u00f9...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.stagnonekiteboarding.com\/en\/team-member\/\" \/>\n<meta property=\"og:site_name\" content=\"Kitesurf Stagnone\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/stagnonekiteboarding\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-22T16:13:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.stagnonekiteboarding.com\\\/team-member\\\/\",\"url\":\"https:\\\/\\\/www.stagnonekiteboarding.com\\\/team-member\\\/\",\"name\":\"Team - Kitesurf Stagnone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.stagnonekiteboarding.com\\\/#website\"},\"datePublished\":\"2018-02-26T10:09:43+00:00\",\"dateModified\":\"2022-01-22T16:13:55+00:00\",\"description\":\"Il Team dello Stagnone Kiteboarding \u00e8 composto da veri e propri professionisti del Kitesurf. Unici del suo genere. Scopri di pi\u00f9...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.stagnonekiteboarding.com\\\/team-member\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.stagnonekiteboarding.com\\\/team-member\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.stagnonekiteboarding.com\\\/team-member\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.stagnonekiteboarding.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Team\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.stagnonekiteboarding.com\\\/#website\",\"url\":\"https:\\\/\\\/www.stagnonekiteboarding.com\\\/\",\"name\":\"Kitesurf Stagnone\",\"description\":\"Scuola Centro Kitesurf Stagnone - Marsala - Trapani - Sicilia\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.stagnonekiteboarding.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.stagnonekiteboarding.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.stagnonekiteboarding.com\\\/#organization\",\"name\":\"Kitesurf Stagnone\",\"url\":\"https:\\\/\\\/www.stagnonekiteboarding.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.stagnonekiteboarding.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.stagnonekiteboarding.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Logo-stagnone-kitesurf.png\",\"contentUrl\":\"https:\\\/\\\/www.stagnonekiteboarding.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Logo-stagnone-kitesurf.png\",\"width\":400,\"height\":200,\"caption\":\"Kitesurf Stagnone\"},\"image\":{\"@id\":\"https:\\\/\\\/www.stagnonekiteboarding.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/stagnonekiteboarding\",\"https:\\\/\\\/www.instagram.com\\\/stagnonekiteboarding\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Team - Kitesurf Stagnone","description":"Il Team dello Stagnone Kiteboarding \u00e8 composto da veri e propri professionisti del Kitesurf. Unici del suo genere. Scopri di pi\u00f9...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.stagnonekiteboarding.com\/en\/team-member\/","og_locale":"en_GB","og_type":"article","og_title":"Team - Kitesurf Stagnone","og_description":"Il Team dello Stagnone Kiteboarding \u00e8 composto da veri e propri professionisti del Kitesurf. Unici del suo genere. Scopri di pi\u00f9...","og_url":"https:\/\/www.stagnonekiteboarding.com\/en\/team-member\/","og_site_name":"Kitesurf Stagnone","article_publisher":"https:\/\/www.facebook.com\/stagnonekiteboarding","article_modified_time":"2022-01-22T16:13:55+00:00","twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.stagnonekiteboarding.com\/team-member\/","url":"https:\/\/www.stagnonekiteboarding.com\/team-member\/","name":"Team - Kitesurf Stagnone","isPartOf":{"@id":"https:\/\/www.stagnonekiteboarding.com\/#website"},"datePublished":"2018-02-26T10:09:43+00:00","dateModified":"2022-01-22T16:13:55+00:00","description":"Il Team dello Stagnone Kiteboarding \u00e8 composto da veri e propri professionisti del Kitesurf. Unici del suo genere. Scopri di pi\u00f9...","breadcrumb":{"@id":"https:\/\/www.stagnonekiteboarding.com\/team-member\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.stagnonekiteboarding.com\/team-member\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.stagnonekiteboarding.com\/team-member\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.stagnonekiteboarding.com\/"},{"@type":"ListItem","position":2,"name":"Team"}]},{"@type":"WebSite","@id":"https:\/\/www.stagnonekiteboarding.com\/#website","url":"https:\/\/www.stagnonekiteboarding.com\/","name":"Kitesurf Stagnone","description":"Scuola Centro Kitesurf Stagnone - Marsala - Trapani - Sicilia","publisher":{"@id":"https:\/\/www.stagnonekiteboarding.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.stagnonekiteboarding.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.stagnonekiteboarding.com\/#organization","name":"Kitesurf Stagnone","url":"https:\/\/www.stagnonekiteboarding.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.stagnonekiteboarding.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.stagnonekiteboarding.com\/wp-content\/uploads\/2020\/11\/Logo-stagnone-kitesurf.png","contentUrl":"https:\/\/www.stagnonekiteboarding.com\/wp-content\/uploads\/2020\/11\/Logo-stagnone-kitesurf.png","width":400,"height":200,"caption":"Kitesurf Stagnone"},"image":{"@id":"https:\/\/www.stagnonekiteboarding.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/stagnonekiteboarding","https:\/\/www.instagram.com\/stagnonekiteboarding"]}]}},"_links":{"self":[{"href":"https:\/\/www.stagnonekiteboarding.com\/en\/wp-json\/wp\/v2\/pages\/1470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stagnonekiteboarding.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.stagnonekiteboarding.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.stagnonekiteboarding.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stagnonekiteboarding.com\/en\/wp-json\/wp\/v2\/comments?post=1470"}],"version-history":[{"count":10,"href":"https:\/\/www.stagnonekiteboarding.com\/en\/wp-json\/wp\/v2\/pages\/1470\/revisions"}],"predecessor-version":[{"id":5300,"href":"https:\/\/www.stagnonekiteboarding.com\/en\/wp-json\/wp\/v2\/pages\/1470\/revisions\/5300"}],"wp:attachment":[{"href":"https:\/\/www.stagnonekiteboarding.com\/en\/wp-json\/wp\/v2\/media?parent=1470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}